<br />
<b>Warning</b>:  Undefined array key "Código de Ur-Namu" in <b>/home/u461346235/domains/advogados.cv/public_html/wp-content/plugins/TooltipProEcommerce/glossaryPro.php</b> on line <b>636</b><br />
<br />
<b>Warning</b>:  Trying to access array offset on value of type null in <b>/home/u461346235/domains/advogados.cv/public_html/wp-content/plugins/TooltipProEcommerce/glossaryPro.php</b> on line <b>636</b><br />
<br />
<b>Warning</b>:  Attempt to read property "post_title" on null in <b>/home/u461346235/domains/advogados.cv/public_html/wp-content/plugins/TooltipProEcommerce/glossaryPro.php</b> on line <b>636</b><br />
<br />
<b>Warning</b>:  Undefined array key "Código de Hamurabi" in <b>/home/u461346235/domains/advogados.cv/public_html/wp-content/plugins/TooltipProEcommerce/glossaryPro.php</b> on line <b>636</b><br />
<br />
<b>Warning</b>:  Trying to access array offset on value of type null in <b>/home/u461346235/domains/advogados.cv/public_html/wp-content/plugins/TooltipProEcommerce/glossaryPro.php</b> on line <b>636</b><br />
<br />
<b>Warning</b>:  Attempt to read property "post_title" on null in <b>/home/u461346235/domains/advogados.cv/public_html/wp-content/plugins/TooltipProEcommerce/glossaryPro.php</b> on line <b>636</b><br />
<br />
<b>Warning</b>:  Undefined array key "Idade Média" in <b>/home/u461346235/domains/advogados.cv/public_html/wp-content/plugins/TooltipProEcommerce/glossaryPro.php</b> on line <b>636</b><br />
<br />
<b>Warning</b>:  Trying to access array offset on value of type null in <b>/home/u461346235/domains/advogados.cv/public_html/wp-content/plugins/TooltipProEcommerce/glossaryPro.php</b> on line <b>636</b><br />
<br />
<b>Warning</b>:  Attempt to read property "post_title" on null in <b>/home/u461346235/domains/advogados.cv/public_html/wp-content/plugins/TooltipProEcommerce/glossaryPro.php</b> on line <b>636</b><br />
<br />
<b>Warning</b>:  Undefined array key "Estado" in <b>/home/u461346235/domains/advogados.cv/public_html/wp-content/plugins/TooltipProEcommerce/glossaryPro.php</b> on line <b>636</b><br />
<br />
<b>Warning</b>:  Trying to access array offset on value of type null in <b>/home/u461346235/domains/advogados.cv/public_html/wp-content/plugins/TooltipProEcommerce/glossaryPro.php</b> on line <b>636</b><br />
<br />
<b>Warning</b>:  Attempt to read property "post_title" on null in <b>/home/u461346235/domains/advogados.cv/public_html/wp-content/plugins/TooltipProEcommerce/glossaryPro.php</b> on line <b>636</b><br />
{"id":1360,"date":"2024-12-05T20:38:43","date_gmt":"2024-12-05T21:38:43","guid":{"rendered":"https:\/\/advogados.cv\/glossary\/lei-penal\/"},"modified":"2024-12-05T20:38:43","modified_gmt":"2024-12-05T21:38:43","slug":"lei-penal","status":"publish","type":"glossary","link":"https:\/\/advogados.cv\/fr\/glossaire\/droit-penal-2\/","title":{"rendered":"Droit p\u00e9nal"},"content":{"rendered":"<p>O <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droit-penal\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">droit p\u00e9nal<\/a><span id=\"cmttFootnoteLink1-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink1\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[1]<\/a><\/sup><\/span> brasileiro &eacute; primariamente regido pelo C&oacute;digo Penal (Decreto-Lei 2848\/40) e opera sob princ&iacute;pios de territorialidade, com leis aplicadas dentro das fronteiras nacionais e em circunst&acirc;ncias internacionais espec&iacute;ficas. A estrutura legal distingue diferentes tipos de leis criminais, incluindo estatutos incriminadores, permissivos e explicativos. Princ&iacute;pios-chave incluem a n&atilde;o retroatividade das leis criminais, com exce&ccedil;&otilde;es que beneficiam os r&eacute;us. O <a class=\"glossaryLink\"  href=\"https:\/\/advogados.cv\/fr\/glossaire\/systeme\/\"  target=\"_blank\"  rel=\"nofollow\"  data-mobile-support=\"0\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>syst\u00e8me<\/a><span id=\"cmttFootnoteLink3-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink3\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[3]<\/a><\/sup><\/span> reconhece diversos cen&aacute;rios jur&iacute;dicos como Abolitio Criminis (descriminaliza&ccedil;&atilde;o), Novatio Legis in Mellius (melhorias legais que beneficiam os r&eacute;us) e Novatio Legis in Pejus (mudan&ccedil;as legais potencialmente desfavor&aacute;veis aos r&eacute;us). As leis criminais s&atilde;o aplicadas com base na teoria da conduta, com predomin&acirc;ncia da <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/jurisdicao\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">juridiction<\/a><span id=\"cmttFootnoteLink2-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink2\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[2]<\/a><\/sup><\/span> federal. O sistema legal permite a aplica&ccedil;&atilde;o extraterritorial da <a class=\"glossaryLink\"  href=\"https:\/\/advogados.cv\/fr\/glossaire\/loi-2\/\"  target=\"_blank\"  rel=\"nofollow\"  data-mobile-support=\"0\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>loi<\/a><span id=\"cmttFootnoteLink4-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink4\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[4]<\/a><\/sup><\/span> brasileira em certas circunst&acirc;ncias e fornece mecanismos para tratar conflitos na legisla&ccedil;&atilde;o criminal ao longo do tempo.<\/p>\n<div class=\"cmtt-footnotes-block\"><div class=\"cmtt-footnote-header\">D\u00e9finitions des termes<\/div><div class=\"cmtt-footnote-header-border\"><\/div><div class=\"cmtt-footnote-def\" id=\"cmttFootnoteLink1\"><span class=\"cmtt-footnote-def-number\">1. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink1-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droit-penal\/\" class=\"glossaryLink\" target=\"_blank\">droit p\u00e9nal<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Le droit p\u00e9nal est un syst\u00e8me juridique complexe qui r\u00e9git la conduite sociale et le comportement criminel. Enracin\u00e9 dans des traditions historiques telles que le droit romain et le droit canonique, il vise \u00e0 prot\u00e9ger les droits fondamentaux tels que la vie, la libert\u00e9 et la propri\u00e9t\u00e9. Il \u00e9tablit un \u00e9quilibre entre le pouvoir de l'\u00c9tat et les droits individuels, en mettant l'accent sur les principes de dignit\u00e9 humaine, de proportionnalit\u00e9 et de respect de la l\u00e9galit\u00e9. Les principes cl\u00e9s sont la l\u00e9galit\u00e9, la pr\u00e9somption d'innocence et l'intervention minimale. Les approches th\u00e9oriques vont du mod\u00e8le r\u00e9tributif (la punition en tant que justice) aux mod\u00e8les pr\u00e9ventif et r\u00e9parateur, ax\u00e9s sur la pr\u00e9vention du crime et la r\u00e9insertion des d\u00e9linquants. Les sources comprennent les codes p\u00e9naux, la l\u00e9gislation en mati\u00e8re de proc\u00e9dure p\u00e9nale et les pr\u00e9c\u00e9dents judiciaires. Des universitaires de renom tels que Roxin, Bitencourt et Figueiredo Dias ont contribu\u00e9 de mani\u00e8re significative \u00e0 son d\u00e9veloppement. Le droit p\u00e9nal cherche en fin de compte \u00e0 maintenir l'ordre social tout en respectant les droits de l'homme individuels, en utilisant les m\u00e9canismes juridiques en dernier recours pour r\u00e9soudre les conflits sociaux. <\/span><\/div><div class=\"cmtt-footnote-def\" id=\"cmttFootnoteLink2\"><span class=\"cmtt-footnote-def-number\">2. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink2-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/jurisdicao\/\" class=\"glossaryLink\" target=\"_blank\">juridiction<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> La comp\u00e9tence est le pouvoir l\u00e9gal d'administrer la justice et de r\u00e9soudre les conflits, traditionnellement associ\u00e9 au pouvoir judiciaire, mais qui englobe aujourd'hui divers organes gouvernementaux. Elle implique des principes tels que l'impartialit\u00e9, l'in\u00e9vitabilit\u00e9 et l'inertie, avec des caract\u00e9ristiques telles que l'application obligatoire et universelle. La comp\u00e9tence peut \u00eatre volontaire (administrative) ou contentieuse (visant \u00e0 la pacification sociale), et ne se limite pas aux proc\u00e9dures judiciaires. Des m\u00e9thodes alternatives de r\u00e9solution des conflits, telles que la m\u00e9diation et l'arbitrage, existent parall\u00e8lement aux proc\u00e9dures judiciaires. Le concept est fondamental pour la proc\u00e9dure civile, impliquant des conditions d'action telles que l'int\u00e9r\u00eat l\u00e9gitime et la possibilit\u00e9 de recours. Les aspects cl\u00e9s comprennent le pouvoir de d\u00e9terminer les questions juridiques, la capacit\u00e9 de substituer la volont\u00e9 des parties et d'assurer une protection judiciaire efficace en tant que droit fondamental. <\/span><\/div><button class=\"cmtt-footnote-showmore-btn\">Afficher plus<\/button><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink3\"><span class=\"cmtt-footnote-def-number\">3. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink3-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/systeme\/\" class=\"glossaryLink\" target=\"_blank\">syst\u00e8me<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Un syst\u00e8me est un arrangement complexe d'\u00e9l\u00e9ments interconnect\u00e9s travaillant \u00e0 la r\u00e9alisation d'un objectif commun. Caract\u00e9ris\u00e9s par l'int\u00e9gration fonctionnelle et la synergie, les syst\u00e8mes peuvent \u00eatre physiques ou conceptuels, allant des organismes biologiques aux structures organisationnelles. Les syst\u00e8mes biologiques suivent une organisation hi\u00e9rarchique allant du niveau atomique au niveau cosmique, tandis que les syst\u00e8mes d'information en informatique se concentrent sur les processus algorithmiques. Les syst\u00e8mes interagissent dynamiquement avec leur environnement par le biais d'entr\u00e9es et de sorties, en maintenant l'hom\u00e9ostasie gr\u00e2ce \u00e0 une communication continue entre les \u00e9l\u00e9ments. Il existe diff\u00e9rents types de syst\u00e8mes dans toutes les disciplines, y compris les syst\u00e8mes biologiques humains tels que les syst\u00e8mes digestifs et nerveux, et les syst\u00e8mes sociaux tels que les structures \u00e9conomiques et juridiques. Le principe fondamental qui sous-tend tous les syst\u00e8mes est l'interd\u00e9pendance des composants, o\u00f9 les changements dans une partie peuvent influencer de mani\u00e8re significative la fonctionnalit\u00e9 et la performance de l'ensemble du syst\u00e8me. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink4\"><span class=\"cmtt-footnote-def-number\">4. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink4-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/loi-2\/\" class=\"glossaryLink\" target=\"_blank\">loi<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Le droit a \u00e9volu\u00e9 \u00e0 travers des \u00e9tapes historiques complexes, depuis les anciens codes \u00e9gyptiens et sum\u00e9riens jusqu'aux syst\u00e8mes juridiques romains sophistiqu\u00e9s. Les civilisations anciennes ont d\u00e9velopp\u00e9 des structures juridiques organis\u00e9es, des innovations significatives apparaissant en Gr\u00e8ce et \u00e0 Rome. Le droit romain, fortement influenc\u00e9 par la philosophie grecque, a \u00e9t\u00e9 syst\u00e9matiquement codifi\u00e9 puis red\u00e9couvert au XIe si\u00e8cle, formant la base des syst\u00e8mes juridiques de l'Europe continentale. Au cours du Moyen \u00c2ge, la coutume et la jurisprudence ont remplac\u00e9 les codes romains rigides, les cours royales anglaises d\u00e9veloppant des pr\u00e9c\u00e9dents de common law. Les syst\u00e8mes juridiques modernes ont vu le jour gr\u00e2ce \u00e0 des codifications influentes telles que les codes civils napol\u00e9onien et allemand, t\u00e9moignant d'une normalisation croissante. Tout au long de l'histoire, le droit a \u00e9t\u00e9 \u00e9troitement li\u00e9 au d\u00e9veloppement de la civilisation, s'adaptant continuellement \u00e0 des contextes sociaux changeants et refl\u00e9tant les identit\u00e9s nationales par le biais d'influences philosophiques, culturelles et professionnelles. <\/span><\/div><\/div><div class=\"cmtt-footnote-bottom-border\"><\/div>","protected":false},"excerpt":{"rendered":"<p>O <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/loi\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">loi<\/a><span id=\"cmttFootnoteLink5-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink5\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[5]<\/a><\/sup><\/span> penal brasileiro &eacute; primariamente regido pelo C&oacute;digo Penal (Decreto-Lei 2848\/40) e opera sob princ&iacute;pios de territorialidade, com leis aplicadas dentro das fronteiras nacionais e em circunst&acirc;ncias internacionais espec&iacute;ficas. A estrutura legal distingue diferentes tipos de leis criminais, incluindo estatutos incriminadores, permissivos e explicativos. Princ&iacute;pios-chave incluem a n&atilde;o retroatividade das leis criminais, com exce&ccedil;&otilde;es [&hellip;]<\/p>\n<div class=\"cmtt-footnotes-block\">\n<div class=\"cmtt-footnote-header\">D\u00e9finitions des termes<\/div>\n<div class=\"cmtt-footnote-header-border\"><\/div>\n<div class=\"cmtt-footnote-def\" id=\"cmttFootnoteLink1\"><span class=\"cmtt-footnote-def-number\">1. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink1-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> \u2191 <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droit-penal\/\" class=\"glossaryLink\" target=\"_blank\">droit p\u00e9nal<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> O direito penal &eacute; um sistema jur&iacute;dico complexo que rege a conduta social e o comportamento criminal. Enraizado em tradi&ccedil;&otilde;es hist&oacute;ricas como o <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droit-romain\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">droit romain<\/a><span id=\"cmttFootnoteLink13-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink13\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[13]<\/a><\/sup><\/span> et <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droit-canon\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">droit canon<\/a><span id=\"cmttFootnoteLink9-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink9\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[9]<\/a><\/sup><\/span>, visa proteger <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droits-fondamentaux\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">droits fondamentaux<\/a><span id=\"cmttFootnoteLink6-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink6\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[6]<\/a><\/sup><\/span> como a vida, a liberdade e a propriedade. O campo equilibra o poder do <a class=\"glossaryLink\"  href=\"https:\/\/advogados.cv\/fr\/glossaire\/etat\/\"  target=\"_blank\"  rel=\"nofollow\"  data-mobile-support=\"0\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>\u00c9tat<\/a><span id=\"cmttFootnoteLink20-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink20\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[20]<\/a><\/sup><\/span> com os direitos individuais, enfatizando princ&iacute;pios de dignidade humana, proporcionalidade e devido processo legal. Princ&iacute;pios-chave incluem a legalidade, presun&ccedil;&atilde;o de inoc&ecirc;ncia e interven&ccedil;&atilde;o m&iacute;nima. As abordagens te&oacute;ricas variam desde o modelo retributivo (puni&ccedil;&atilde;o como <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/justica\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">justice<\/a><span id=\"cmttFootnoteLink18-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink18\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[18]<\/a><\/sup><\/span>) at&eacute; modelos preventivos e restaurativos, focando na preven&ccedil;&atilde;o do crime e reabilita&ccedil;&atilde;o do infrator. As fontes incluem c&oacute;digos penais, legisla&ccedil;&atilde;o de processo penal e precedentes judiciais. Estudiosos not&aacute;veis como Roxin, Bitencourt e Figueiredo Dias contribu&iacute;ram significativamente para o seu desenvolvimento. O direito penal procura, em &uacute;ltima an&aacute;lise, manter a ordem social respeitando os <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droits-de-lhomme\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">droits de l'homme<\/a><span id=\"cmttFootnoteLink10-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink10\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[10]<\/a><\/sup><\/span> individuais, utilizando mecanismos legais como &uacute;ltimo recurso para abordar conflitos sociais. <\/span><\/div>\n<div class=\"cmtt-footnote-def\" id=\"cmttFootnoteLink2\"><span class=\"cmtt-footnote-def-number\">2. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink2-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> \u2191 <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/jurisdicao\/\" class=\"glossaryLink\" target=\"_blank\">juridiction<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> La comp\u00e9tence est le pouvoir l\u00e9gal d'administrer la justice et de r\u00e9soudre les conflits, traditionnellement associ\u00e9 au pouvoir judiciaire, mais qui englobe aujourd'hui divers organes gouvernementaux. Elle implique des principes tels que l'impartialit\u00e9, l'in\u00e9vitabilit\u00e9 et l'inertie, avec des caract\u00e9ristiques telles que l'application obligatoire et universelle. La comp\u00e9tence peut \u00eatre volontaire (administrative) ou contentieuse (visant \u00e0 la pacification sociale), et ne se limite pas aux proc\u00e9dures judiciaires. Des m\u00e9thodes alternatives de r\u00e9solution des conflits, telles que la m\u00e9diation et l'arbitrage, existent parall\u00e8lement aux proc\u00e9dures judiciaires. Le concept est fondamental pour la proc\u00e9dure civile, impliquant des conditions d'action telles que l'int\u00e9r\u00eat l\u00e9gitime et la possibilit\u00e9 de recours. Les aspects cl\u00e9s comprennent le pouvoir de d\u00e9terminer les questions juridiques, la capacit\u00e9 de substituer la volont\u00e9 des parties et d'assurer une protection judiciaire efficace en tant que droit fondamental. <\/span><\/div>\n<p><button class=\"cmtt-footnote-showmore-btn\">Afficher plus<\/button><\/p>\n<div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink3\"><span class=\"cmtt-footnote-def-number\">3. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink3-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> \u2191 <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/systeme\/\" class=\"glossaryLink\" target=\"_blank\">syst\u00e8me<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Un syst\u00e8me est un arrangement complexe d'\u00e9l\u00e9ments interconnect\u00e9s travaillant \u00e0 la r\u00e9alisation d'un objectif commun. Caract\u00e9ris\u00e9s par l'int\u00e9gration fonctionnelle et la synergie, les syst\u00e8mes peuvent \u00eatre physiques ou conceptuels, allant des organismes biologiques aux structures organisationnelles. Les syst\u00e8mes biologiques suivent une organisation hi\u00e9rarchique allant du niveau atomique au niveau cosmique, tandis que les syst\u00e8mes d'information en informatique se concentrent sur les processus algorithmiques. Les syst\u00e8mes interagissent dynamiquement avec leur environnement par le biais d'entr\u00e9es et de sorties, en maintenant l'hom\u00e9ostasie gr\u00e2ce \u00e0 <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/comunicacao\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">communication<\/a><span id=\"cmttFootnoteLink14-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink14\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[14]<\/a><\/sup><\/span> entre les \u00e9l\u00e9ments. Il existe diff\u00e9rents types de syst\u00e8mes dans toutes les disciplines, y compris les syst\u00e8mes biologiques humains tels que les syst\u00e8mes digestifs et nerveux, et les syst\u00e8mes sociaux tels que les structures \u00e9conomiques et juridiques. Le principe fondamental qui sous-tend tous les syst\u00e8mes est l'interd\u00e9pendance des composants, les modifications d'une partie pouvant influencer de mani\u00e8re significative la fonctionnalit\u00e9 et les performances de l'ensemble du syst\u00e8me. <\/span><\/div>\n<div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink4\"><span class=\"cmtt-footnote-def-number\">4. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink4-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> \u2191 <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/loi-2\/\" class=\"glossaryLink\" target=\"_blank\">loi<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Le droit a \u00e9volu\u00e9 \u00e0 travers des \u00e9tapes historiques complexes, depuis les anciens codes \u00e9gyptiens et sum\u00e9riens jusqu'aux syst\u00e8mes juridiques romains sophistiqu\u00e9s. Les civilisations anciennes ont d\u00e9velopp\u00e9 des structures juridiques organis\u00e9es, des innovations significatives apparaissant en Gr\u00e8ce et \u00e0 Rome. Le droit romain, fortement influenc\u00e9 par la philosophie grecque, a \u00e9t\u00e9 syst\u00e9matiquement codifi\u00e9 puis red\u00e9couvert au XIe si\u00e8cle, formant la base des syst\u00e8mes juridiques de l'Europe continentale. Au cours de la <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/idade-media\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Moyen \u00c2ge<\/a><span id=\"cmttFootnoteLink15-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink15\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[15]<\/a><\/sup><\/span>, o <a class=\"glossaryLink\"  href=\"https:\/\/advogados.cv\/fr\/glossaire\/sur-mesure\/\"  target=\"_blank\"  rel=\"nofollow\"  data-mobile-support=\"0\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>sur mesure<\/a><span id=\"cmttFootnoteLink21-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink21\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[21]<\/a><\/sup><\/span> et <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/jurisprudencia\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">jurisprudence<\/a><span id=\"cmttFootnoteLink11-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink11\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[11]<\/a><\/sup><\/span> substitu&iacute;ram os c&oacute;digos romanos r&iacute;gidos, com os tribunais reais ingleses desenvolvendo precedentes de direito comum. Os sistemas jur&iacute;dicos modernos emergiram com codifica&ccedil;&otilde;es influentes como os c&oacute;digos civis napole&ocirc;nicos e alem&atilde;es, demonstrando uma padroniza&ccedil;&atilde;o crescente. Ao longo da hist&oacute;ria, o direito esteve intimamente conectado ao desenvolvimento da <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/civilizacao\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">civilisation<\/a><span id=\"cmttFootnoteLink16-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink16\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[16]<\/a><\/sup><\/span>, adaptando-se continuamente a contextos sociais mut&aacute;veis e refletindo identidades nacionais atrav&eacute;s de influ&ecirc;ncias filos&oacute;ficas, culturais e profissionais. <\/span><\/div>\n<div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink5\"><span class=\"cmtt-footnote-def-number\">5. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink5-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> \u2191 <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/loi\/\" class=\"glossaryLink\" target=\"_blank\">loi<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Le droit est un syst\u00e8me complexe de r\u00e8gles qui r\u00e9gissent le comportement humain par le biais de droits et de devoirs, fa\u00e7onn\u00e9s par diverses influences sociales et culturelles. D'origine latine et sanskrite, il englobe diff\u00e9rentes familles juridiques telles que le <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droit-civil\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">droit civil<\/a><span id=\"cmttFootnoteLink17-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink17\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[17]<\/a><\/sup><\/span> et la common law. Le domaine fait une large distinction entre <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droit-public\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">droit public<\/a><span id=\"cmttFootnoteLink12-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink12\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[12]<\/a><\/sup><\/span> et priv\u00e9, s'adressant respectivement aux int\u00e9r\u00eats des entreprises et des particuliers. Ses fondements remontent aux soci\u00e9t\u00e9s archa\u00efques, avec les premi\u00e8res codifications telles que le <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/codigo-de-ur-namu\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Code de l'Ur-Namu<\/a><span id=\"cmttFootnoteLink7-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink7\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[7]<\/a><\/sup><\/span> et <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/code-dhamurabi\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Code d'Hammourabi<\/a><span id=\"cmttFootnoteLink8-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink8\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[8]<\/a><\/sup><\/span>. O direito romano avan&ccedil;ou significativamente os sistemas jur&iacute;dicos, separando o direito da <a class=\"glossaryLink\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/religiao\/\" target=\"_blank\" rel=\"nofollow\" data-mobile-support=\"0\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">religion<\/a><span id=\"cmttFootnoteLink19-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink19\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[19]<\/a><\/sup><\/span> e da moralidade, e desenvolvendo conceitos jur&iacute;dicos sofisticados. O direito moderno prov&eacute;m de m&uacute;ltiplas fontes, incluindo legisla&ccedil;&atilde;o estadual, tratados internacionais e contratos individuais. Tribunais e &oacute;rg&atilde;os jurisdicionais aplicam normas jur&iacute;dicas atrav&eacute;s de interpreta&ccedil;&atilde;o guiada por doutrina, <a class=\"glossaryLink\"  href=\"https:\/\/advogados.cv\/fr\/glossaire\/douanes\/\"  target=\"_blank\"  rel=\"nofollow\"  data-mobile-support=\"0\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>douanes<\/a><span id=\"cmttFootnoteLink22-0\" class=\"cmtt-footnote\"><sup><a class=\"et_smooth_scroll_disabled cmtt_footnote_link cmtt-footnote-deflink\" href=\"#cmttFootnoteLink22\" style=\"font-size: 14px; color: #325afb; font-style : none ;\">[22]<\/a><\/sup><\/span> e precedentes judiciais, refletindo a natureza din&acirc;mica e adaptativa do direito. <\/span><\/div>\n<\/div>\n<div class=\"cmtt-footnote-bottom-border\"><\/div>\n<div class=\"cmtt-footnotes-block\"><div class=\"cmtt-footnote-header\">D\u00e9finitions des termes<\/div><div class=\"cmtt-footnote-header-border\"><\/div><div class=\"cmtt-footnote-def\" id=\"cmttFootnoteLink1\"><span class=\"cmtt-footnote-def-number\">1. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink1-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droit-penal\/\" class=\"glossaryLink\" target=\"_blank\">droit p\u00e9nal<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Le droit p\u00e9nal est un syst\u00e8me juridique complexe qui r\u00e9git la conduite sociale et le comportement criminel. Enracin\u00e9 dans des traditions historiques telles que le droit romain et le droit canonique, il vise \u00e0 prot\u00e9ger les droits fondamentaux tels que la vie, la libert\u00e9 et la propri\u00e9t\u00e9. Il \u00e9tablit un \u00e9quilibre entre le pouvoir de l'\u00c9tat et les droits individuels, en mettant l'accent sur les principes de dignit\u00e9 humaine, de proportionnalit\u00e9 et de respect de la l\u00e9galit\u00e9. Les principes cl\u00e9s sont la l\u00e9galit\u00e9, la pr\u00e9somption d'innocence et l'intervention minimale. Les approches th\u00e9oriques vont du mod\u00e8le r\u00e9tributif (la punition en tant que justice) aux mod\u00e8les pr\u00e9ventif et r\u00e9parateur, ax\u00e9s sur la pr\u00e9vention du crime et la r\u00e9insertion des d\u00e9linquants. Les sources comprennent les codes p\u00e9naux, la l\u00e9gislation en mati\u00e8re de proc\u00e9dure p\u00e9nale et les pr\u00e9c\u00e9dents judiciaires. Des universitaires de renom tels que Roxin, Bitencourt et Figueiredo Dias ont contribu\u00e9 de mani\u00e8re significative \u00e0 son d\u00e9veloppement. Le droit p\u00e9nal cherche en fin de compte \u00e0 maintenir l'ordre social tout en respectant les droits de l'homme individuels, en utilisant les m\u00e9canismes juridiques en dernier recours pour r\u00e9soudre les conflits sociaux. <\/span><\/div><div class=\"cmtt-footnote-def\" id=\"cmttFootnoteLink2\"><span class=\"cmtt-footnote-def-number\">2. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink2-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/jurisdicao\/\" class=\"glossaryLink\" target=\"_blank\">juridiction<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> La comp\u00e9tence est le pouvoir l\u00e9gal d'administrer la justice et de r\u00e9soudre les conflits, traditionnellement associ\u00e9 au pouvoir judiciaire, mais qui englobe aujourd'hui divers organes gouvernementaux. Elle implique des principes tels que l'impartialit\u00e9, l'in\u00e9vitabilit\u00e9 et l'inertie, avec des caract\u00e9ristiques telles que l'application obligatoire et universelle. La comp\u00e9tence peut \u00eatre volontaire (administrative) ou contentieuse (visant \u00e0 la pacification sociale), et ne se limite pas aux proc\u00e9dures judiciaires. Des m\u00e9thodes alternatives de r\u00e9solution des conflits, telles que la m\u00e9diation et l'arbitrage, existent parall\u00e8lement aux proc\u00e9dures judiciaires. Le concept est fondamental pour la proc\u00e9dure civile, impliquant des conditions d'action telles que l'int\u00e9r\u00eat l\u00e9gitime et la possibilit\u00e9 de recours. Les aspects cl\u00e9s comprennent le pouvoir de d\u00e9terminer les questions juridiques, la capacit\u00e9 de substituer la volont\u00e9 des parties et d'assurer une protection judiciaire efficace en tant que droit fondamental. <\/span><\/div><button class=\"cmtt-footnote-showmore-btn\">Afficher plus<\/button><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink3\"><span class=\"cmtt-footnote-def-number\">3. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink3-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/systeme\/\" class=\"glossaryLink\" target=\"_blank\">syst\u00e8me<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Un syst\u00e8me est un arrangement complexe d'\u00e9l\u00e9ments interconnect\u00e9s travaillant \u00e0 la r\u00e9alisation d'un objectif commun. Caract\u00e9ris\u00e9s par l'int\u00e9gration fonctionnelle et la synergie, les syst\u00e8mes peuvent \u00eatre physiques ou conceptuels, allant des organismes biologiques aux structures organisationnelles. Les syst\u00e8mes biologiques suivent une organisation hi\u00e9rarchique allant du niveau atomique au niveau cosmique, tandis que les syst\u00e8mes d'information en informatique se concentrent sur les processus algorithmiques. Les syst\u00e8mes interagissent dynamiquement avec leur environnement par le biais d'entr\u00e9es et de sorties, en maintenant l'hom\u00e9ostasie gr\u00e2ce \u00e0 une communication continue entre les \u00e9l\u00e9ments. Il existe diff\u00e9rents types de syst\u00e8mes dans toutes les disciplines, y compris les syst\u00e8mes biologiques humains tels que les syst\u00e8mes digestifs et nerveux, et les syst\u00e8mes sociaux tels que les structures \u00e9conomiques et juridiques. Le principe fondamental qui sous-tend tous les syst\u00e8mes est l'interd\u00e9pendance des composants, o\u00f9 les changements dans une partie peuvent influencer de mani\u00e8re significative la fonctionnalit\u00e9 et la performance de l'ensemble du syst\u00e8me. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink4\"><span class=\"cmtt-footnote-def-number\">4. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink4-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/loi-2\/\" class=\"glossaryLink\" target=\"_blank\">loi<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Le droit a \u00e9volu\u00e9 \u00e0 travers des \u00e9tapes historiques complexes, depuis les anciens codes \u00e9gyptiens et sum\u00e9riens jusqu'aux syst\u00e8mes juridiques romains sophistiqu\u00e9s. Les civilisations anciennes ont d\u00e9velopp\u00e9 des structures juridiques organis\u00e9es, des innovations significatives apparaissant en Gr\u00e8ce et \u00e0 Rome. Le droit romain, fortement influenc\u00e9 par la philosophie grecque, a \u00e9t\u00e9 syst\u00e9matiquement codifi\u00e9 puis red\u00e9couvert au XIe si\u00e8cle, formant la base des syst\u00e8mes juridiques de l'Europe continentale. Au cours du Moyen \u00c2ge, la coutume et la jurisprudence ont remplac\u00e9 les codes romains rigides, les cours royales anglaises d\u00e9veloppant des pr\u00e9c\u00e9dents de common law. Les syst\u00e8mes juridiques modernes ont vu le jour gr\u00e2ce \u00e0 des codifications influentes telles que les codes civils napol\u00e9onien et allemand, t\u00e9moignant d'une normalisation croissante. Tout au long de l'histoire, le droit a \u00e9t\u00e9 \u00e9troitement li\u00e9 au d\u00e9veloppement de la civilisation, s'adaptant continuellement \u00e0 des contextes sociaux changeants et refl\u00e9tant les identit\u00e9s nationales par le biais d'influences philosophiques, culturelles et professionnelles. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink5\"><span class=\"cmtt-footnote-def-number\">5. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink5-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/loi\/\" class=\"glossaryLink\" target=\"_blank\">loi<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Le droit est un syst\u00e8me complexe de r\u00e8gles qui r\u00e9gissent le comportement humain par le biais de droits et de devoirs, fa\u00e7onn\u00e9s par diverses influences sociales et culturelles. D'origine latine et sanskrite, il englobe diff\u00e9rentes familles juridiques telles que le droit civil et la common law. Le domaine fait largement la distinction entre le droit public et le droit priv\u00e9, qui traitent respectivement des int\u00e9r\u00eats des entreprises et des particuliers. Ses fondements remontent aux soci\u00e9t\u00e9s archa\u00efques, avec les premi\u00e8res codifications telles que le code d'Ur-Namu et le code d'Hammurabi. Le droit romain a fait progresser de mani\u00e8re significative les syst\u00e8mes juridiques, en s\u00e9parant le droit de la religion et de la morale, et en d\u00e9veloppant des concepts juridiques sophistiqu\u00e9s. Le droit moderne provient de sources multiples, notamment de la l\u00e9gislation des \u00c9tats, des trait\u00e9s internationaux et des contrats individuels. Les cours et tribunaux appliquent les normes juridiques par le biais d'une interpr\u00e9tation guid\u00e9e par la doctrine, la coutume et les pr\u00e9c\u00e9dents judiciaires, ce qui refl\u00e8te la nature dynamique et adaptative du droit. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink6\"><span class=\"cmtt-footnote-def-number\">6. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink6-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droits-fondamentaux\/\" class=\"glossaryLink\" target=\"_blank\">droits fondamentaux<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Les droits fondamentaux peuvent entrer en conflit dans la pratique, m\u00eame si les normes constitutionnelles ne sont pas structur\u00e9es de mani\u00e8re hi\u00e9rarchique. Lorsque des droits entrent en conflit, le principe de proportionnalit\u00e9 sert de m\u00e9canisme cl\u00e9 de r\u00e9solution, impliquant une \u00e9valuation minutieuse de l'ad\u00e9quation, de la n\u00e9cessit\u00e9 et d'une consid\u00e9ration \u00e9quilibr\u00e9e. La jurisprudence br\u00e9silienne, en particulier la Cour supr\u00eame, reconna\u00eet l'effet direct des droits fondamentaux sur les relations priv\u00e9es, bien que la litt\u00e9rature juridique internationale continue de d\u00e9battre de l'\u00e9tendue et de la port\u00e9e de cette application. Parmi les exemples pratiques, on peut citer les tensions entre la libert\u00e9 de la presse et le droit \u00e0 la vie priv\u00e9e, les limitations dans des situations critiques telles que les enl\u00e8vements, et la r\u00e9solution de sc\u00e9narios complexes dans les contextes de l'emploi, de la famille et de la propri\u00e9t\u00e9. Des universitaires tels que Sarlet, Canotilho et Rolim ont \u00e9tudi\u00e9 en profondeur ces dynamiques, soulignant l'approche nuanc\u00e9e n\u00e9cessaire pour optimiser la protection des droits tout en \u00e9vitant des restrictions disproportionn\u00e9es des libert\u00e9s individuelles. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink7\"><span class=\"cmtt-footnote-def-number\">7. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink7-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/codigo-de-ur-namu\/\" class=\"glossaryLink\" target=\"_blank\">Code de l'Ur-Namu<\/a> ( Code de l'Ur-Namu ) <\/span><span class=\"cmtt-footnote-def-content\"> Le code d'Ur-Nammu, l'un des plus anciens codes juridiques connus de l'ancienne M\u00e9sopotamie, fournit des informations d\u00e9taill\u00e9es sur les premi\u00e8res r\u00e9glementations sociales. Cr\u00e9\u00e9 par le roi Ur-Nammu de la ville sum\u00e9rienne d'Ur, le code \u00e9tablit des principes de justice uniformes qui couvrent divers aspects de la vie sociale. Il pr\u00e9voit des sanctions sp\u00e9cifiques pour des crimes tels que le meurtre, le vol, l'agression et les d\u00e9lits sexuels, en prescrivant g\u00e9n\u00e9ralement des compensations financi\u00e8res ou, dans les cas les plus graves, des condamnations \u00e0 mort. Le cadre juridique abordait des sc\u00e9narios sociaux complexes tels que le divorce, les conflits de propri\u00e9t\u00e9 et les conflits interpersonnels. Le code a notamment fait preuve d'une r\u00e9flexion juridique sophistiqu\u00e9e en pr\u00e9voyant des peines gradu\u00e9es en fonction de la gravit\u00e9 des d\u00e9lits et en \u00e9tablissant une distinction entre les classes sociales. Il prot\u00e8ge \u00e9galement les groupes vuln\u00e9rables tels que les veuves et les orphelins, r\u00e9v\u00e9lant ainsi une compr\u00e9hension avanc\u00e9e de l'\u00e9quit\u00e9 sociale. L'approche syst\u00e9matique du code a consid\u00e9rablement influenc\u00e9 les syst\u00e8mes juridiques ult\u00e9rieurs du Proche-Orient ancien. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink8\"><span class=\"cmtt-footnote-def-number\">8. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink8-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/code-dhamurabi\/\" class=\"glossaryLink\" target=\"_blank\">Code d'Hammourabi<\/a> (Code d'Hammourabi) <\/span><span class=\"cmtt-footnote-def-content\"> Le code d'Hammourabi, d\u00e9couvert en 1901 \u00e0 Suse, est un important document juridique m\u00e9sopotamien datant d'environ 1750 avant J.-C. Sculpt\u00e9 dans un monument de pierre avec 282 lois, il repr\u00e9sente l'un des plus anciens codes juridiques \u00e9crits complets. Le code \u00e9tablit le principe \"\u0153il pour \u0153il\" et introduit un syst\u00e8me juridique qui diff\u00e9rencie les peines en fonction de la classe sociale. Il couvre divers aspects de la soci\u00e9t\u00e9, notamment les contrats, les affaires familiales, l'esclavage et les infractions p\u00e9nales. Les lois \u00e9taient structur\u00e9es de mani\u00e8re \u00e0 prot\u00e9ger les faibles, \u00e0 unifier le royaume babylonien et \u00e0 fournir un cadre juridique standard. Leur influence s'est \u00e9tendue aux syst\u00e8mes juridiques ult\u00e9rieurs, y compris le droit isra\u00e9lite. En pr\u00e9sentant les lois comme immuables et sanctionn\u00e9es par Dieu, le code d'Hammourabi t\u00e9moigne d'une compr\u00e9hension approfondie de la jurisprudence et de l'organisation sociale dans l'ancienne M\u00e9sopotamie. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink9\"><span class=\"cmtt-footnote-def-number\">9. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink9-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droit-canon\/\" class=\"glossaryLink\" target=\"_blank\">droit canon<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> <div class=\"cmtt_meanings_wrapper\"><div><span class=\"cmtt_meaning_label\">1 <\/span><span class=\"cmtt_meaning_definition\">Le droit canonique englobe les syst\u00e8mes juridiques de diverses confessions chr\u00e9tiennes, r\u00e9glementant la gouvernance, l'appartenance et les pratiques eccl\u00e9siastiques. Le droit canonique de l'\u00c9glise catholique, codifi\u00e9 en 1983, d\u00e9coule de multiples traditions juridiques historiques et s'applique aux \u00c9glises catholiques latine et orientale. Le droit canonique anglican a \u00e9volu\u00e9 des tribunaux eccl\u00e9siastiques vers les tribunaux royaux apr\u00e8s la R\u00e9forme. Le droit canonique orthodoxe, rassembl\u00e9 dans le Pedalion, met l'accent sur la flexibilit\u00e9 et les adaptations locales, tout en maintenant les principes dogmatiques fondamentaux. Les \u00e9glises presbyt\u00e9riennes et r\u00e9form\u00e9es d\u00e9veloppent des pratiques eccl\u00e9siastiques par le biais d'une gouvernance d\u00e9centralis\u00e9e, tandis que le luth\u00e9ranisme se concentre sur les d\u00e9clarations doctrinales du Livre de la Concorde plut\u00f4t que sur des structures juridiques globales. Les \u00c9glises m\u00e9thodistes s'appuient sur le livre de discipline, qui fournit des lignes directrices pour la structure organisationnelle, les principes th\u00e9ologiques et les pratiques op\u00e9rationnelles. Le droit canonique de chaque d\u00e9nomination refl\u00e8te son contexte historique, culturel et th\u00e9ologique unique, servant \u00e0 maintenir l'ordre eccl\u00e9siastique et la coh\u00e9sion spirituelle.<\/span><\/div><div><span class=\"cmtt_meaning_label\">2 <\/span><span class=\"cmtt_meaning_definition\">Le droit canonique est un syst\u00e8me juridique complet qui r\u00e9git les organisations religieuses chr\u00e9tiennes, principalement l'\u00c9glise catholique, les \u00c9glises orthodoxes et la Communion anglicane. Issu des premi\u00e8res r\u00e8gles eccl\u00e9siastiques \u00e9tablies par les ap\u00f4tres, il int\u00e8gre diverses traditions juridiques, notamment des influences h\u00e9bra\u00efques, romaines et celtiques. Le syst\u00e8me catholique actuel est d\u00e9fini par deux codes principaux : le code de droit canonique de 1917 et la version r\u00e9vis\u00e9e de 1983, qui contient 1 752 canons r\u00e9gissant la gouvernance et les proc\u00e9dures de l'\u00c9glise. Les \u00c9glises catholiques orientales disposent d'un code canonique distinct promulgu\u00e9 en 1990. Le droit canonique a \u00e9volu\u00e9 de mani\u00e8re significative \u00e0 partir des syst\u00e8mes juridiques eccl\u00e9siastiques m\u00e9di\u00e9vaux, avec des d\u00e9veloppements historiques importants tels que le d\u00e9cret de Gratien et les d\u00e9cr\u00e9tales papales. Il continue \u00e0 fa\u00e7onner les pratiques institutionnelles religieuses, \u00e0 se croiser avec le droit civil et \u00e0 aborder les questions \u00e9thiques et sociales contemporaines. Les \u00e9tudes universitaires, les associations r\u00e9gionales et les ressources du Vatican soutiennent la recherche et l'interpr\u00e9tation du droit canonique.<\/span><\/div><\/div> <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink10\"><span class=\"cmtt-footnote-def-number\">10. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink10-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droits-de-lhomme\/\" class=\"glossaryLink\" target=\"_blank\">droits de l'homme<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Les droits de l'homme sont des libert\u00e9s et des protections fondamentales inh\u00e9rentes \u00e0 tous les \u00eatres humains, ind\u00e9pendamment de leur race, de leur sexe, de leur nationalit\u00e9 ou de leur statut. Enracin\u00e9s dans les traditions philosophiques des droits naturels et des th\u00e9ories du contrat social, ils englobent des dimensions civiles, politiques, \u00e9conomiques, sociales et culturelles. Le mod\u00e8le moderne des droits de l'homme est apparu apr\u00e8s la Seconde Guerre mondiale, la D\u00e9claration universelle des droits de l'homme des Nations unies en \u00e9tant la pierre angulaire. Des syst\u00e8mes internationaux et r\u00e9gionaux tels que la Convention europ\u00e9enne des droits de l'homme et la Commission interam\u00e9ricaine ont d\u00e9velopp\u00e9 des m\u00e9canismes pour contr\u00f4ler et faire respecter ces droits. Des organisations de premier plan, telles qu'Amnesty International et Human Rights Watch, d\u00e9fendent la dignit\u00e9 humaine dans le monde entier. Les d\u00e9fis contemporains consistent \u00e0 rem\u00e9dier aux violations persistantes, \u00e0 trouver un \u00e9quilibre entre les principes universels et les contextes culturels et \u00e0 faire face aux questions \u00e9mergentes telles que les droits num\u00e9riques et la protection de l'environnement. Le domaine continue d'\u00e9voluer, refl\u00e9tant la dynamique mondiale complexe de la justice, de l'\u00e9galit\u00e9 et de la dignit\u00e9 humaine. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink11\"><span class=\"cmtt-footnote-def-number\">11. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink11-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/jurisprudencia\/\" class=\"glossaryLink\" target=\"_blank\">jurisprudence<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> La jurisprudence est l'\u00e9tude syst\u00e9matique des principes juridiques et des d\u00e9cisions judiciaires, qui trouve son origine dans le droit romain et se d\u00e9veloppe \u00e0 travers la common law anglaise. Elle englobe l'interpr\u00e9tation et l'application des lois par les tribunaux, ce qui permet de combler les lacunes juridiques et de s'adapter aux besoins de la soci\u00e9t\u00e9 contemporaine. Les d\u00e9cisions judiciaires fournissent des orientations essentielles pour la pratique juridique, des bases de donn\u00e9es sp\u00e9cialis\u00e9es aidant les juristes \u00e0 naviguer dans des paysages juridiques complexes. Alors que les lois ont une application plus large et sont cr\u00e9\u00e9es par des processus l\u00e9gislatifs, les d\u00e9cisions de justice offrent des interpr\u00e9tations sp\u00e9cifiques et des pr\u00e9c\u00e9dents au sein d'une juridiction donn\u00e9e. Cette discipline joue un r\u00f4le crucial dans la compr\u00e9hension des coutumes juridiques, la r\u00e9solution des litiges et la coh\u00e9rence du raisonnement judiciaire. La jurisprudence moderne s'appuie sur des solutions technologiques pour classer et analyser les d\u00e9cisions de justice, ce qui permet d'am\u00e9liorer l'efficacit\u00e9 de la recherche et de l'interpr\u00e9tation juridiques. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink12\"><span class=\"cmtt-footnote-def-number\">12. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink12-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droit-public\/\" class=\"glossaryLink\" target=\"_blank\">droit public<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> La division entre le droit public et le droit priv\u00e9 d\u00e9coule des traditions juridiques romaines, en particulier de la distinction d'Ulpiano entre le jus publicum et le jus privatum. Cette classification s\u00e9pare les r\u00e8gles juridiques en fonction des int\u00e9r\u00eats (publics ou priv\u00e9s), des types de relations juridiques (coordination ou imposition) et des formes d'interaction (imp\u00e9ratif ou autonomie). Le droit public couvre le droit international, constitutionnel, administratif, p\u00e9nal, financier et fiscal, tandis que le droit priv\u00e9 s'est affaibli \u00e0 mesure que l'\u00c9tat intervenait de plus en plus dans les domaines juridiques. Les critiques de cette division portent sur le manque de pr\u00e9cision, la simplification excessive des complexit\u00e9s juridiques et la diff\u00e9renciation insuffisante entre les int\u00e9r\u00eats individuels et collectifs. Les interpr\u00e9tations modernes consid\u00e8rent la constitution comme le fondement de tout le droit national, brouillant les fronti\u00e8res traditionnelles et sugg\u00e9rant que tout le droit devient potentiellement public. La s\u00e9paration refl\u00e8te l'\u00e9volution de la relation entre l'\u00c9tat et la soci\u00e9t\u00e9, soulignant la nature dynamique de la cat\u00e9gorisation juridique. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink13\"><span class=\"cmtt-footnote-def-number\">13. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink13-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droit-romain\/\" class=\"glossaryLink\" target=\"_blank\">droit romain<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Le droit romain englobe les r\u00e8gles juridiques \u00e9labor\u00e9es \u00e0 Rome et dans son empire de 449 avant J.-C. \u00e0 530 apr\u00e8s J.-C., \u00e9voluant \u00e0 travers quatre grandes p\u00e9riodes. D'abord nationaliste et li\u00e9 aux pratiques religieuses, il est progressivement devenu plus universel et plus complexe. Les Douze Tablettes, le premier texte juridique \u00e9crit de Rome, ont marqu\u00e9 une transition cruciale du droit coutumier au droit codifi\u00e9, en traitant des proc\u00e9dures, des jugements et des droits de propri\u00e9t\u00e9. Sous Justinien, d'importantes compilations juridiques telles que le Corpus Juris Civilis ont \u00e9t\u00e9 cr\u00e9\u00e9es, int\u00e9grant les concepts juridiques grecs et les constitutions imp\u00e9riales. Le droit romain a profond\u00e9ment influenc\u00e9 les syst\u00e8mes juridiques d'Europe et d'Am\u00e9rique latine, en \u00e9tablissant les principes fondamentaux du droit priv\u00e9 et du droit public. Son h\u00e9ritage comprend le d\u00e9veloppement du professionnalisme juridique, de la jurisprudence et des structures visant \u00e0 harmoniser les normes juridiques, ce qui en fait un mod\u00e8le crucial pour la compr\u00e9hension des syst\u00e8mes juridiques historiques et contemporains. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink14\"><span class=\"cmtt-footnote-def-number\">14. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink14-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/comunicacao\/\" class=\"glossaryLink\" target=\"_blank\">communication<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> La communication est un processus complexe d'\u00e9change d'informations par le biais de signes, de symboles et de canaux technologiques. \u00c9voluant des formes orales et \u00e9crites aux plateformes num\u00e9riques, elle englobe diff\u00e9rents modes, dont la communication verbale, non verbale et m\u00e9diatis\u00e9e. Apparue au d\u00e9but du XXe si\u00e8cle, la th\u00e9orie de la communication explore la structure et la signification sociale de l'interaction humaine dans diff\u00e9rents contextes, tels que les domaines interpersonnels, organisationnels et interculturels. La s\u00e9miotique joue un r\u00f4le crucial pour comprendre comment les pens\u00e9es et les sentiments sont transform\u00e9s en signes compr\u00e9hensibles. Les avanc\u00e9es technologiques, en particulier les ordinateurs et les r\u00e9seaux sociaux, continuent de remodeler les processus de communication, passant des m\u00e9dias de masse traditionnels aux r\u00e9seaux collaboratifs. Le domaine s'inspire de disciplines humanistes telles que la philosophie, la sociologie et la psychologie, examinant la communication comme un ph\u00e9nom\u00e8ne social dynamique qui refl\u00e8te la connectivit\u00e9 humaine et l'\u00e9change d'informations. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink15\"><span class=\"cmtt-footnote-def-number\">15. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink15-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/idade-media\/\" class=\"glossaryLink\" target=\"_blank\">Moyen \u00c2ge<\/a> ( Moyen \u00c2ge ) <\/span><span class=\"cmtt-footnote-def-content\"> Le Moyen \u00c2ge, traditionnellement d\u00e9fini comme la p\u00e9riode comprise entre 476 et 1500 apr\u00e8s J.-C., est une p\u00e9riode historique complexe caract\u00e9ris\u00e9e par d'importantes transformations soci\u00e9tales. Apr\u00e8s la chute de l'Empire romain d'Occident, de nouveaux royaumes sont apparus gr\u00e2ce aux migrations et \u00e0 l'int\u00e9gration culturelle. L'\u00e9poque est divis\u00e9e entre le haut et le bas Moyen \u00c2ge, le premier \u00e9tant marqu\u00e9 par la croissance d\u00e9mographique, le f\u00e9odalisme et des r\u00e9alisations culturelles telles que les cath\u00e9drales gothiques, tandis que le second a connu des d\u00e9fis tels que les guerres, les famines et la peste noire. D'abord consid\u00e9r\u00e9e comme un \"\u00e2ge des t\u00e9n\u00e8bres\", cette p\u00e9riode a \u00e9t\u00e9 r\u00e9\u00e9valu\u00e9e par les chercheurs modernes, qui y voient une p\u00e9riode dynamique de d\u00e9veloppement culturel et technologique. La ferveur religieuse, les expansions territoriales, les changements dans les r\u00e9seaux commerciaux et les interactions entre diff\u00e9rentes civilisations telles que les royaumes byzantins, islamiques et les nouveaux royaumes europ\u00e9ens en sont les principales caract\u00e9ristiques. La p\u00e9riode s'est finalement transform\u00e9e en Renaissance, repr\u00e9sentant une phase critique dans l'\u00e9volution historique de l'Europe. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink16\"><span class=\"cmtt-footnote-def-number\">16. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink16-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/civilizacao\/\" class=\"glossaryLink\" target=\"_blank\">civilisation<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Le concept de civilisation englobe des transformations socioculturelles complexes induites par des r\u00e9volutions technologiques et repr\u00e9sentant des changements dynamiques dans l'organisation sociale de l'humanit\u00e9. Les civilisations se caract\u00e9risent par des identit\u00e9s culturelles uniques, englobant des id\u00e9es, des coutumes, des arts et des pratiques de fabrication distincts qui tendent \u00e0 se r\u00e9pandre et \u00e0 influencer d'autres sph\u00e8res culturelles. Des chercheurs tels que Samuel Huntington et Darcy Ribeiro ont propos\u00e9 diff\u00e9rents cadres pour comprendre le d\u00e9veloppement civilisationnel, en identifiant de multiples zones culturelles et trajectoires historiques. Ces perspectives explorent la mani\u00e8re dont les soci\u00e9t\u00e9s \u00e9voluent \u00e0 travers des changements technologiques, sociaux et culturels, soulignant la nature non lin\u00e9aire de la progression humaine. L'\u00e9tude des civilisations implique l'analyse des processus d'h\u00e9g\u00e9monie culturelle, d'autor\u00e9gulation sociale et des conflits potentiels d\u00e9coulant des diff\u00e9rences id\u00e9ologiques et culturelles. Le concept va au-del\u00e0 des simples structures sociales, repr\u00e9sentant une identit\u00e9 culturelle plus large et englobant des mod\u00e8les complexes d'interaction et de transformation humaines. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink17\"><span class=\"cmtt-footnote-def-number\">17. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink17-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/droit-civil\/\" class=\"glossaryLink\" target=\"_blank\">droit civil<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Le droit civil est un syst\u00e8me juridique complet qui r\u00e9git les relations priv\u00e9es dans diverses juridictions. Issu du droit romain (Ius Civile), il englobe des principes d'\u00e9thique, de sociabilit\u00e9 et d'op\u00e9rabilit\u00e9. Ce syst\u00e8me influence de multiples traditions juridiques, y compris le droit civil br\u00e9silien, qui a subi d'importantes transformations au fil des codifications historiques. Le code civil br\u00e9silien, \u00e9tabli en 2002 (loi n\u00b0 10.406), a remplac\u00e9 les structures juridiques pr\u00e9c\u00e9dentes et introduit des changements progressifs tels que l'abaissement de l'\u00e2ge de la majorit\u00e9 civile \u00e0 18 ans, l'autorisation de l'\u00e9mancipation parentale \u00e0 partir de 16 ans et la garantie de l'\u00e9galit\u00e9 des droits pour les enfants artificiels et naturels. Sa structure comprend une partie g\u00e9n\u00e9rale, une partie sp\u00e9ciale et une partie compl\u00e9mentaire, qui traitent de divers domaines juridiques. Le code refl\u00e8te l'\u00e9volution des normes sociales en promouvant l'\u00e9galit\u00e9 des sexes et en adaptant les d\u00e9finitions juridiques aux contextes sociaux contemporains, d\u00e9montrant ainsi la nature dynamique du droit civil dans la r\u00e9gulation des interactions et des droits des citoyens. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink18\"><span class=\"cmtt-footnote-def-number\">18. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink18-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/justica\/\" class=\"glossaryLink\" target=\"_blank\">justice<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> La justice est un concept philosophique et social complexe qui a \u00e9t\u00e9 examin\u00e9 sous diff\u00e9rents angles au cours de diff\u00e9rentes p\u00e9riodes historiques. Les philosophes de la Gr\u00e8ce antique, tels que Socrate et Aristote, ont explor\u00e9 ses dimensions subjectives et correctives, tandis que les penseurs m\u00e9di\u00e9vaux, tels que Thomas d'Aquin, ont reli\u00e9 la justice \u00e0 la volont\u00e9 divine. Les th\u00e9oriciens modernes tels que Rawls, Sen et Dworkin offrent diverses perspectives sur l'\u00e9quit\u00e9, l'\u00e9galit\u00e9 et l'organisation sociale. Parmi les approches cl\u00e9s, citons les points de vue utilitaires qui mettent l'accent sur le bonheur collectif, les perspectives libertaires qui donnent la priorit\u00e9 aux droits individuels et les cadres fond\u00e9s sur les capacit\u00e9s qui mettent l'accent sur le potentiel humain. Les universitaires d\u00e9battent des principes fondamentaux de la justice, en examinant la r\u00e9partition des ressources, des opportunit\u00e9s et des biens sociaux. Symboliquement repr\u00e9sent\u00e9e par une balance, une \u00e9p\u00e9e et des personnages aux yeux band\u00e9s, la justice incarne l'impartialit\u00e9, l'\u00e9quilibre et la prise de d\u00e9cision rationnelle. Le discours contemporain continue d'explorer la mani\u00e8re dont la justice peut \u00eatre r\u00e9alis\u00e9e par le biais de m\u00e9canismes juridiques, \u00e9conomiques et philosophiques, en reconnaissant sa nature dynamique et multiforme. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink19\"><span class=\"cmtt-footnote-def-number\">19. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink19-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/religiao\/\" class=\"glossaryLink\" target=\"_blank\">religion<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> La religion est un concept complexe qui a vu le jour au XVIIe si\u00e8cle et qui englobe diverses croyances, pratiques et traditions culturelles. \u00c9tudi\u00e9e dans de multiples disciplines, elle implique des rituels, des r\u00e9cits et des \u00e9l\u00e9ments spirituels qui transcendent souvent la vie quotidienne. Les principales religions du monde comprennent le christianisme, l'islam, l'hindouisme et le bouddhisme, repr\u00e9sentant collectivement plus de 77% de la population mondiale. Les approches acad\u00e9miques examinent la religion \u00e0 travers des perspectives sociologiques, philosophiques et cognitives, explorant ses origines dans des exp\u00e9riences humaines telles que la conscience communautaire et la mortalit\u00e9. Les d\u00e9finitions varient consid\u00e9rablement et ne font pas l'objet d'un consensus acad\u00e9mique strict. Les pratiques religieuses vont des c\u00e9r\u00e9monies formelles aux exp\u00e9riences spirituelles personnelles et comportent souvent des dimensions surnaturelles ou transcendantales. Dans le monde, environ 59-63% des personnes se consid\u00e8rent comme religieuses, avec des variations entre les diff\u00e9rents groupes d\u00e9mographiques. Le concept continue d'\u00e9voluer, remettant en question les fronti\u00e8res traditionnelles entre les domaines s\u00e9culier et spirituel. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink20\"><span class=\"cmtt-footnote-def-number\">20. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink20-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/etat\/\" class=\"glossaryLink\" target=\"_blank\">\u00c9tat<\/a> ( \u00c9tat ) <\/span><span class=\"cmtt-footnote-def-content\"> Un \u00c9tat est une entit\u00e9 souveraine dot\u00e9e de limites territoriales d\u00e9finies, d'une population et d'une gouvernance autonome. Issu du mot latin \"status\", il est n\u00e9 du d\u00e9clin du f\u00e9odalisme et a \u00e9t\u00e9 formellement reconnu par la paix de Westphalie en 1648. Les \u00c9tats exercent leur autorit\u00e9 souveraine par l'interm\u00e9diaire d'institutions qui \u00e9laborent et appliquent les lois, g\u00e8rent les affaires \u00e9conomiques et fournissent des services publics. Ils peuvent \u00eatre structur\u00e9s comme des syst\u00e8mes unitaires ou f\u00e9d\u00e9raux, des monarchies ou des r\u00e9publiques, chacun ayant des caract\u00e9ristiques organisationnelles distinctes. Les principales fonctions sont le maintien de la s\u00e9curit\u00e9, la collecte des imp\u00f4ts, la fourniture de biens publics et la repr\u00e9sentation des int\u00e9r\u00eats nationaux au niveau international. Le concept d'\u00c9tat a \u00e9t\u00e9 largement influenc\u00e9 par des philosophes politiques tels que Hobbes et Locke et fa\u00e7onn\u00e9 par des \u00e9v\u00e9nements historiques tels que la R\u00e9volution fran\u00e7aise. Son \u00e9volution se poursuit en r\u00e9ponse aux d\u00e9fis mondiaux et aux dynamiques sociopolitiques changeantes. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink21\"><span class=\"cmtt-footnote-def-number\">21. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink21-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/sur-mesure\/\" class=\"glossaryLink\" target=\"_blank\">sur mesure<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Les coutumes sont des r\u00e8gles sociales issues de pratiques anciennes et r\u00e9pandues, qui \u00e9tablissent des obligations soci\u00e9tales et repr\u00e9sentent des valeurs culturelles essentielles. Elles \u00e9voluent gr\u00e2ce \u00e0 des interactions sociales r\u00e9p\u00e9t\u00e9es et \u00e0 des convictions subjectives, et se distinguent des cadres juridiques en aspirant \u00e0 la validit\u00e9 plut\u00f4t qu'\u00e0 la simple efficacit\u00e9. Le concept couvre divers domaines, des pratiques traditionnelles aux normes comportementales, qui peuvent passer d'un \u00e9tat interdit \u00e0 un \u00e9tat reconnu au fil du temps. Dans les contextes juridiques, les d\u00e9lits d'habitude refl\u00e8tent la dangerosit\u00e9 sociale et le potentiel de d\u00e9linquance d'un individu, qui apparaissent souvent lorsque les mesures punitives pr\u00e9c\u00e9dentes se r\u00e9v\u00e8lent inefficaces. Les concepts interdisciplinaires connexes comprennent le droit coutumier, l'anthropologie juridique et les \u00e9tudes comportementales. Pour comprendre les coutumes, il faut analyser leur contexte historique et culturel et reconna\u00eetre comment les pratiques sociales se d\u00e9veloppent, se transforment et s'int\u00e8grent dans des structures soci\u00e9tales sp\u00e9cifiques. <\/span><\/div><div class=\"cmtt-footnote-def hidden\" id=\"cmttFootnoteLink22\"><span class=\"cmtt-footnote-def-number\">22. <\/span><span class=\"cmtt-footnote-def-back\"><a class=\"cmtt_footnote_link cmtt-footnote-backlink\" href=\"#cmttFootnoteLink22-0\" style=\"font-size: 14px; color: #325afb; font-style : none ;\"> &#8593; <\/a><\/span><span class=\"cmtt-footnote-def-key\"> <a aria-describedby=\"tt\" href=\"https:\/\/advogados.cv\/fr\/glossaire\/douanes\/\" class=\"glossaryLink\" target=\"_blank\">douanes<\/a>. <\/span><span class=\"cmtt-footnote-def-content\"> Les coutumes sont des r\u00e8gles sociales issues de pratiques r\u00e9p\u00e9t\u00e9es dans un contexte culturel sp\u00e9cifique, caract\u00e9ris\u00e9es par des \u00e9l\u00e9ments objectifs (corpus consuetudo) et subjectifs (animus). Elles refl\u00e8tent la conviction psychologique des obligations comportementales dans diff\u00e9rentes soci\u00e9t\u00e9s. Ces pratiques couvrent diff\u00e9rents domaines, y compris des perspectives juridiques, sociales et anthropologiques. Les exemples vont des comportements traditionnels aux activit\u00e9s criminelles potentielles, telles que le curandeirismo et la capoeira. Sur le plan juridique, les coutumes \u00e9tablissent une distinction entre les infractions habituelles et les infractions typiques, en se concentrant sur la perception sociale des pratiques. D'un point de vue sociologique, elles repr\u00e9sentent des valeurs essentielles et transmettent des normes culturelles qui d\u00e9finissent un comportement acceptable. Les coutumes sont intrins\u00e8quement li\u00e9es \u00e0 des concepts plus larges tels que l'habitus, le droit coutumier et l'anthropologie juridique, d\u00e9montrant comment les pratiques sociales \u00e9voluent et se normalisent dans des cadres culturels sp\u00e9cifiques. Elles servent de prisme \u00e0 travers lequel les soci\u00e9t\u00e9s comprennent et cat\u00e9gorisent le comportement humain. <\/span><\/div><\/div><div class=\"cmtt-footnote-bottom-border\"><\/div>","protected":false},"author":1,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"glossary-categories":[],"glossary-tags":[],"glossary-languages":[],"class_list":["post-1360","glossary","type-glossary","status-publish","hentry"],"post_title":"Lei penal","post_content":"O direito penal brasileiro \u00e9 primariamente regido pelo C\u00f3digo Penal (Decreto-Lei 2848\/40) e opera sob princ\u00edpios de territorialidade, com leis aplicadas dentro das fronteiras nacionais e em circunst\u00e2ncias internacionais espec\u00edficas. A estrutura legal distingue diferentes tipos de leis criminais, incluindo estatutos incriminadores, permissivos e explicativos. Princ\u00edpios-chave incluem a n\u00e3o retroatividade das leis criminais, com exce\u00e7\u00f5es que beneficiam os r\u00e9us. O sistema reconhece diversos cen\u00e1rios jur\u00eddicos como Abolitio Criminis (descriminaliza\u00e7\u00e3o), Novatio Legis in Mellius (melhorias legais que beneficiam os r\u00e9us) e Novatio Legis in Pejus (mudan\u00e7as legais potencialmente desfavor\u00e1veis aos r\u00e9us). As leis criminais s\u00e3o aplicadas com base na teoria da conduta, com predomin\u00e2ncia da jurisdi\u00e7\u00e3o federal. O sistema legal permite a aplica\u00e7\u00e3o extraterritorial da lei brasileira em certas circunst\u00e2ncias e fornece mecanismos para tratar conflitos na legisla\u00e7\u00e3o criminal ao longo do tempo.","acf":[],"_links":{"self":[{"href":"https:\/\/advogados.cv\/fr\/wp-json\/wp\/v2\/glossary\/1360"}],"collection":[{"href":"https:\/\/advogados.cv\/fr\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/advogados.cv\/fr\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/advogados.cv\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/advogados.cv\/fr\/wp-json\/wp\/v2\/glossary\/1360\/revisions"}],"wp:attachment":[{"href":"https:\/\/advogados.cv\/fr\/wp-json\/wp\/v2\/media?parent=1360"}],"wp:term":[{"taxonomy":"glossary-categories","embeddable":true,"href":"https:\/\/advogados.cv\/fr\/wp-json\/wp\/v2\/glossary-categories?post=1360"},{"taxonomy":"glossary-tags","embeddable":true,"href":"https:\/\/advogados.cv\/fr\/wp-json\/wp\/v2\/glossary-tags?post=1360"},{"taxonomy":"glossary-languages","embeddable":true,"href":"https:\/\/advogados.cv\/fr\/wp-json\/wp\/v2\/glossary-languages?post=1360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}